{"id":208,"count":173,"description":"","link":"https:\/\/www.correiobraziliense.com.br\/aqui\/categoria\/ciencia\/","name":"Ci\u00eancia","slug":"ciencia","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Arquivo de Ci\u00eancia - Correio Braziliense - Aqui<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.correiobraziliense.com.br\/aqui\/categoria\/ciencia\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arquivo de Ci\u00eancia - Correio Braziliense - Aqui\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.correiobraziliense.com.br\/aqui\/categoria\/ciencia\/\" \/>\n<meta property=\"og:site_name\" content=\"Correio Braziliense - Aqui\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.correiobraziliense.com.br\/aqui\/wp-content\/uploads\/2025\/05\/Logo-Aqui_sem-slogan-e1747965560488.png\" \/>\n\t<meta property=\"og:image:width\" content=\"256\" \/>\n\t<meta property=\"og:image:height\" content=\"130\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Arquivo de Ci\u00eancia - Correio Braziliense - Aqui","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.correiobraziliense.com.br\/aqui\/categoria\/ciencia\/","og_locale":"pt_BR","og_type":"article","og_title":"Arquivo de Ci\u00eancia - Correio Braziliense - Aqui","og_url":"https:\/\/www.correiobraziliense.com.br\/aqui\/categoria\/ciencia\/","og_site_name":"Correio Braziliense - Aqui","og_image":[{"width":256,"height":130,"url":"https:\/\/www.correiobraziliense.com.br\/aqui\/wp-content\/uploads\/2025\/05\/Logo-Aqui_sem-slogan-e1747965560488.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.correiobraziliense.com.br\/aqui\/categoria\/ciencia\/","url":"https:\/\/www.correiobraziliense.com.br\/aqui\/categoria\/ciencia\/","name":"Arquivo de Ci\u00eancia - Correio Braziliense - Aqui","isPartOf":{"@id":"https:\/\/www.correiobraziliense.com.br\/aqui\/#website"},"breadcrumb":{"@id":"https:\/\/www.correiobraziliense.com.br\/aqui\/categoria\/ciencia\/#breadcrumb"},"inLanguage":"pt-BR"},{"@type":"BreadcrumbList","@id":"https:\/\/www.correiobraziliense.com.br\/aqui\/categoria\/ciencia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.correiobraziliense.com.br\/aqui\/"},{"@type":"ListItem","position":2,"name":"Ci\u00eancia"}]},{"@type":"WebSite","@id":"https:\/\/www.correiobraziliense.com.br\/aqui\/#website","url":"https:\/\/www.correiobraziliense.com.br\/aqui\/","name":"Correio Braziliense - Aqui","description":"O Correio Braziliense (CB) \u00e9 o mais importante canal de not\u00edcias de Bras\u00edlia. Aqui voc\u00ea encontra as \u00faltimas not\u00edcias do DF, do Brasil e do mundo.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.correiobraziliense.com.br\/aqui\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"}]}},"_links":{"self":[{"href":"https:\/\/www.correiobraziliense.com.br\/aqui\/wp-json\/wp\/v2\/categories\/208","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.correiobraziliense.com.br\/aqui\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.correiobraziliense.com.br\/aqui\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.correiobraziliense.com.br\/aqui\/wp-json\/wp\/v2\/posts?categories=208"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}