{"id":16783,"count":2,"description":"","link":"https:\/\/www.correiobraziliense.com.br\/cbradar\/tag\/perfumes-da-o-boticario\/","name":"perfumes da O Botic\u00e1rio","slug":"perfumes-da-o-boticario","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Arquivo de perfumes da O Botic\u00e1rio - Correio Braziliense - Radar<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.correiobraziliense.com.br\/cbradar\/tag\/perfumes-da-o-boticario\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arquivo de perfumes da O Botic\u00e1rio - Correio Braziliense - Radar\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.correiobraziliense.com.br\/cbradar\/tag\/perfumes-da-o-boticario\/\" \/>\n<meta property=\"og:site_name\" content=\"Correio Braziliense - Radar\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Arquivo de perfumes da O Botic\u00e1rio - Correio Braziliense - Radar","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.correiobraziliense.com.br\/cbradar\/tag\/perfumes-da-o-boticario\/","og_locale":"pt_BR","og_type":"article","og_title":"Arquivo de perfumes da O Botic\u00e1rio - Correio Braziliense - Radar","og_url":"https:\/\/www.correiobraziliense.com.br\/cbradar\/tag\/perfumes-da-o-boticario\/","og_site_name":"Correio Braziliense - Radar","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.correiobraziliense.com.br\/cbradar\/tag\/perfumes-da-o-boticario\/","url":"https:\/\/www.correiobraziliense.com.br\/cbradar\/tag\/perfumes-da-o-boticario\/","name":"Arquivo de perfumes da O Botic\u00e1rio - Correio Braziliense - Radar","isPartOf":{"@id":"https:\/\/www.correiobraziliense.com.br\/cbradar\/#website"},"breadcrumb":{"@id":"https:\/\/www.correiobraziliense.com.br\/cbradar\/tag\/perfumes-da-o-boticario\/#breadcrumb"},"inLanguage":"pt-BR"},{"@type":"BreadcrumbList","@id":"https:\/\/www.correiobraziliense.com.br\/cbradar\/tag\/perfumes-da-o-boticario\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.correiobraziliense.com.br\/cbradar\/"},{"@type":"ListItem","position":2,"name":"perfumes da O Botic\u00e1rio"}]},{"@type":"WebSite","@id":"https:\/\/www.correiobraziliense.com.br\/cbradar\/#website","url":"https:\/\/www.correiobraziliense.com.br\/cbradar\/","name":"Correio Braziliense - Radar","description":"Acompanhe as \u00faltimas not\u00edcias e fique bem informado sobre tudo o que acontece no Brasil e no mundo.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.correiobraziliense.com.br\/cbradar\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"}]}},"_links":{"self":[{"href":"https:\/\/www.correiobraziliense.com.br\/cbradar\/wp-json\/wp\/v2\/tags\/16783","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.correiobraziliense.com.br\/cbradar\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.correiobraziliense.com.br\/cbradar\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.correiobraziliense.com.br\/cbradar\/wp-json\/wp\/v2\/posts?tags=16783"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}