{"id":23479,"count":1,"description":"","link":"https:\/\/www.correiobraziliense.com.br\/cbradar\/tag\/beneficios-do-mel-de-manuka\/","name":"benef\u00edcios do mel de Manuka","slug":"beneficios-do-mel-de-manuka","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Arquivo de benef\u00edcios do mel de Manuka - Correio Braziliense - Radar<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.correiobraziliense.com.br\/cbradar\/tag\/beneficios-do-mel-de-manuka\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arquivo de benef\u00edcios do mel de Manuka - Correio Braziliense - Radar\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.correiobraziliense.com.br\/cbradar\/tag\/beneficios-do-mel-de-manuka\/\" \/>\n<meta property=\"og:site_name\" content=\"Correio Braziliense - Radar\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.correiobraziliense.com.br\/cbradar\/wp-content\/uploads\/2026\/07\/correio-logo.png\" \/>\n\t<meta property=\"og:image:width\" content=\"387\" \/>\n\t<meta property=\"og:image:height\" content=\"49\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Arquivo de benef\u00edcios do mel de Manuka - Correio Braziliense - Radar","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.correiobraziliense.com.br\/cbradar\/tag\/beneficios-do-mel-de-manuka\/","og_locale":"pt_BR","og_type":"article","og_title":"Arquivo de benef\u00edcios do mel de Manuka - Correio Braziliense - Radar","og_url":"https:\/\/www.correiobraziliense.com.br\/cbradar\/tag\/beneficios-do-mel-de-manuka\/","og_site_name":"Correio Braziliense - Radar","og_image":[{"width":387,"height":49,"url":"https:\/\/www.correiobraziliense.com.br\/cbradar\/wp-content\/uploads\/2026\/07\/correio-logo.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.correiobraziliense.com.br\/cbradar\/tag\/beneficios-do-mel-de-manuka\/","url":"https:\/\/www.correiobraziliense.com.br\/cbradar\/tag\/beneficios-do-mel-de-manuka\/","name":"Arquivo de benef\u00edcios do mel de Manuka - Correio Braziliense - Radar","isPartOf":{"@id":"https:\/\/www.correiobraziliense.com.br\/cbradar\/#website"},"breadcrumb":{"@id":"https:\/\/www.correiobraziliense.com.br\/cbradar\/tag\/beneficios-do-mel-de-manuka\/#breadcrumb"},"inLanguage":"pt-BR"},{"@type":"BreadcrumbList","@id":"https:\/\/www.correiobraziliense.com.br\/cbradar\/tag\/beneficios-do-mel-de-manuka\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.correiobraziliense.com.br\/cbradar\/"},{"@type":"ListItem","position":2,"name":"benef\u00edcios do mel de Manuka"}]},{"@type":"WebSite","@id":"https:\/\/www.correiobraziliense.com.br\/cbradar\/#website","url":"https:\/\/www.correiobraziliense.com.br\/cbradar\/","name":"Correio Braziliense - Radar","description":"Acompanhe as \u00faltimas not\u00edcias e fique bem informado sobre tudo o que acontece no Brasil e no mundo.","publisher":{"@id":"https:\/\/www.correiobraziliense.com.br\/cbradar\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.correiobraziliense.com.br\/cbradar\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.correiobraziliense.com.br\/cbradar\/#organization","name":"Correio Braziliense","url":"https:\/\/www.correiobraziliense.com.br\/cbradar\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.correiobraziliense.com.br\/cbradar\/#\/schema\/logo\/image\/","url":"https:\/\/www.correiobraziliense.com.br\/cbradar\/wp-content\/uploads\/2026\/07\/correio-logo.png","contentUrl":"https:\/\/www.correiobraziliense.com.br\/cbradar\/wp-content\/uploads\/2026\/07\/correio-logo.png","width":387,"height":49,"caption":"Correio Braziliense"},"image":{"@id":"https:\/\/www.correiobraziliense.com.br\/cbradar\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.correiobraziliense.com.br\/cbradar\/wp-json\/wp\/v2\/tags\/23479","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.correiobraziliense.com.br\/cbradar\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.correiobraziliense.com.br\/cbradar\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.correiobraziliense.com.br\/cbradar\/wp-json\/wp\/v2\/posts?tags=23479"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}